{"id":217,"count":3,"description":"","link":"https:\/\/www.salkantaytrilha.com\/blog\/tag\/palccoyo\/","name":"Palccoyo","slug":"palccoyo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arquivo de Palccoyo - informa\u00e7\u00f5es de viagens<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Palccoyo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salkantaytrilha.com\/blog\/tag\/palccoyo\/\" \/>\n<meta property=\"og:site_name\" content=\"informa\u00e7\u00f5es de viagens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@salkantayperu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/tag\\\/palccoyo\\\/\",\"url\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/tag\\\/palccoyo\\\/\",\"name\":\"Arquivo de Palccoyo - informa\u00e7\u00f5es de viagens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/tag\\\/palccoyo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/tag\\\/palccoyo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palccoyo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/\",\"name\":\"informa\u00e7\u00f5es de viagens a Machu Picchu\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/#organization\",\"name\":\"informa\u00e7\u00f5es de viagens a Machu Picchu\",\"url\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/salkantaytrekking-new-300x128-1.png\",\"contentUrl\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/salkantaytrekking-new-300x128-1.png\",\"width\":300,\"height\":128,\"caption\":\"informa\u00e7\u00f5es de viagens a Machu Picchu\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salkantaytrilha.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalkantayTrekking\\\/\",\"https:\\\/\\\/x.com\\\/salkantayperu\",\"https:\\\/\\\/www.pinterest.com\\\/salkantaytrekking\\\/\",\"https:\\\/\\\/www.instagram.com\\\/salkantaytrekking\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salkantaytrekking\",\"https:\\\/\\\/www.tiktok.com\\\/@salkantaytrekking\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arquivo de Palccoyo - informa\u00e7\u00f5es de viagens","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Palccoyo","og_url":"https:\/\/www.salkantaytrilha.com\/blog\/tag\/palccoyo\/","og_site_name":"informa\u00e7\u00f5es de viagens","twitter_card":"summary_large_image","twitter_site":"@salkantayperu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.salkantaytrilha.com\/blog\/tag\/palccoyo\/","url":"https:\/\/www.salkantaytrilha.com\/blog\/tag\/palccoyo\/","name":"Arquivo de Palccoyo - informa\u00e7\u00f5es de viagens","isPartOf":{"@id":"https:\/\/www.salkantaytrilha.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.salkantaytrilha.com\/blog\/tag\/palccoyo\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salkantaytrilha.com\/blog\/tag\/palccoyo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.salkantaytrilha.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Palccoyo"}]},{"@type":"WebSite","@id":"https:\/\/www.salkantaytrilha.com\/blog\/#website","url":"https:\/\/www.salkantaytrilha.com\/blog\/","name":"informa\u00e7\u00f5es de viagens a Machu Picchu","description":"","publisher":{"@id":"https:\/\/www.salkantaytrilha.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salkantaytrilha.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.salkantaytrilha.com\/blog\/#organization","name":"informa\u00e7\u00f5es de viagens a Machu Picchu","url":"https:\/\/www.salkantaytrilha.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salkantaytrilha.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salkantaytrilha.com\/blog\/wp-content\/uploads\/2024\/05\/salkantaytrekking-new-300x128-1.png","contentUrl":"https:\/\/www.salkantaytrilha.com\/blog\/wp-content\/uploads\/2024\/05\/salkantaytrekking-new-300x128-1.png","width":300,"height":128,"caption":"informa\u00e7\u00f5es de viagens a Machu Picchu"},"image":{"@id":"https:\/\/www.salkantaytrilha.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalkantayTrekking\/","https:\/\/x.com\/salkantayperu","https:\/\/www.pinterest.com\/salkantaytrekking\/","https:\/\/www.instagram.com\/salkantaytrekking\/","https:\/\/www.youtube.com\/user\/salkantaytrekking","https:\/\/www.tiktok.com\/@salkantaytrekking"]}]}},"_links":{"self":[{"href":"https:\/\/www.salkantaytrilha.com\/blog\/wp-json\/wp\/v2\/tags\/217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salkantaytrilha.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.salkantaytrilha.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.salkantaytrilha.com\/blog\/wp-json\/wp\/v2\/posts?tags=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}